{"id":18443,"date":"2015-09-16T20:57:56","date_gmt":"2015-09-16T11:57:56","guid":{"rendered":"http:\/\/www.tenji.tv\/?p=18443"},"modified":"2019-05-09T11:14:10","modified_gmt":"2019-05-09T02:14:10","slug":"%e6%b8%ac%e5%ae%9a%e8%a8%88%e6%b8%ac%e5%b1%95-2015-%e5%8d%93%e4%b8%8a%e5%9e%8b%e9%ab%98%e9%80%9f3d%e3%82%b9%e3%82%ad%e3%83%a3%e3%83%8a%e3%80%8crvl6540%e3%80%8d-%e6%97%a5%e6%9c%ac%e9%9b%bb%e7%94%a3","status":"publish","type":"post","link":"https:\/\/www.tenji.tv\/japan\/video\/2015\/measuring-technology-expo_2015\/measuring-technology-expo_2015-exhibitor\/%e6%b8%ac%e5%ae%9a%e8%a8%88%e6%b8%ac%e5%b1%95-2015-%e5%8d%93%e4%b8%8a%e5%9e%8b%e9%ab%98%e9%80%9f3d%e3%82%b9%e3%82%ad%e3%83%a3%e3%83%8a%e3%80%8crvl6540%e3%80%8d-%e6%97%a5%e6%9c%ac%e9%9b%bb%e7%94%a3\/","title":{"rendered":"[\u6e2c\u5b9a\u8a08\u6e2c\u5c55 2015] \u5353\u4e0a\u578b\u9ad8\u901f3D\u30b9\u30ad\u30e3\u30ca\u300cRVL6540\u300d - \u65e5\u672c\u96fb\u7523\u30c8\u30fc\u30bd\u30af\u682a\u5f0f\u4f1a\u793e"},"content":{"rendered":"<p>\u65e5\u672c\u96fb\u7523\u30c8\u30fc\u30bd\u30af\u682a\u5f0f\u4f1a\u793e\u306f\u6e2c\u5b9a\u8a08\u6e2c\u5c55 2015\u306b\u3066\u3001\u5353\u4e0a\u578b\u9ad8\u901f3D\u30b9\u30ad\u30e3\u30ca\u300cRVL6540\u300d\u3092\u51fa\u5c55\u3002<br \/>\n\u30e9\u30a4\u30f3\u30ec\u30fc\u30b6\u30fc\u306b\u3088\u308b\u5149\u5207\u65ad\u65b9\u5f0f\u3092\u63a1\u7528\u3057\u305f\u5353\u4e0a\u578b\u9ad8\u901f3D\u30b9\u30ad\u30e3\u30ca\u30fc\u3092\u7d39\u4ecb\u3002<\/p>\n<p>\u8a73\u7d30\u306f\u30a4\u30f3\u30bf\u30fc\u30cd\u30c3\u30c8\u5c55\u793a\u4f1a.tv\u3078\uff01 https:\/\/www.tenji.tv\/japan<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u65e5\u672c\u96fb\u7523\u30c8\u30fc\u30bd\u30af\u682a\u5f0f\u4f1a\u793e\u306f\u6e2c\u5b9a\u8a08\u6e2c\u5c55 2015\u306b\u3066\u3001\u5353\u4e0a\u578b\u9ad8\u901f3D\u30b9\u30ad\u30e3\u30ca\u300cRVL6540\u300d\u3092\u51fa\u5c55\u3002 \u30e9\u30a4\u30f3\u30ec\u30fc\u30b6\u30fc\u306b\u3088\u308b\u5149\u5207\u65ad\u65b9\u5f0f\u3092\u63a1\u7528\u3057\u305f\u5353\u4e0a\u578b\u9ad8\u901f3D\u30b9\u30ad\u30e3\u30ca\u30fc\u3092\u7d39\u4ecb\u3002 \u8a73\u7d30\u306f\u30a4\u30f3\u30bf\u30fc\u30cd\u30c3\u30c8\u5c55\u793a\u4f1a.tv\u3078\uff01 htt [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":18461,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":""},"categories":[687],"tags":[1217,1218],"class_list":["post-18443","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-measuring-technology-expo_2015-exhibitor","tag-information-telecommunication","tag-machinery-industrial-technology","post_format-post-format-video"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>[\u6e2c\u5b9a\u8a08\u6e2c\u5c55 2015] \u5353\u4e0a\u578b\u9ad8\u901f3D\u30b9\u30ad\u30e3\u30ca\u300cRVL6540\u300d - \u65e5\u672c\u96fb\u7523\u30c8\u30fc\u30bd\u30af\u682a\u5f0f\u4f1a\u793e \uff5c\u5c55\u793a\u4f1a\u52d5\u753b\uff5c\u30a4\u30f3\u30bf\u30fc\u30cd\u30c3\u30c8\u5c55\u793a\u4f1a.tv<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tenji.tv\/japan\/video\/2015\/measuring-technology-expo_2015\/measuring-technology-expo_2015-exhibitor\/\u6e2c\u5b9a\u8a08\u6e2c\u5c55-2015-\u5353\u4e0a\u578b\u9ad8\u901f3d\u30b9\u30ad\u30e3\u30ca\u300crvl6540\u300d-\u65e5\u672c\u96fb\u7523\/\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[\u6e2c\u5b9a\u8a08\u6e2c\u5c55 2015] \u5353\u4e0a\u578b\u9ad8\u901f3D\u30b9\u30ad\u30e3\u30ca\u300cRVL6540\u300d - \u65e5\u672c\u96fb\u7523\u30c8\u30fc\u30bd\u30af\u682a\u5f0f\u4f1a\u793e \uff5c\u5c55\u793a\u4f1a\u52d5\u753b\uff5c\u30a4\u30f3\u30bf\u30fc\u30cd\u30c3\u30c8\u5c55\u793a\u4f1a.tv\" \/>\n<meta property=\"og:description\" content=\"\u65e5\u672c\u96fb\u7523\u30c8\u30fc\u30bd\u30af\u682a\u5f0f\u4f1a\u793e\u306f\u6e2c\u5b9a\u8a08\u6e2c\u5c55 2015\u306b\u3066\u3001\u5353\u4e0a\u578b\u9ad8\u901f3D\u30b9\u30ad\u30e3\u30ca\u300cRVL6540\u300d\u3092\u51fa\u5c55\u3002 \u30e9\u30a4\u30f3\u30ec\u30fc\u30b6\u30fc\u306b\u3088\u308b\u5149\u5207\u65ad\u65b9\u5f0f\u3092\u63a1\u7528\u3057\u305f\u5353\u4e0a\u578b\u9ad8\u901f3D\u30b9\u30ad\u30e3\u30ca\u30fc\u3092\u7d39\u4ecb\u3002 \u8a73\u7d30\u306f\u30a4\u30f3\u30bf\u30fc\u30cd\u30c3\u30c8\u5c55\u793a\u4f1a.tv\u3078\uff01 htt [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tenji.tv\/japan\/video\/2015\/measuring-technology-expo_2015\/measuring-technology-expo_2015-exhibitor\/\u6e2c\u5b9a\u8a08\u6e2c\u5c55-2015-\u5353\u4e0a\u578b\u9ad8\u901f3d\u30b9\u30ad\u30e3\u30ca\u300crvl6540\u300d-\u65e5\u672c\u96fb\u7523\/\" \/>\n<meta property=\"og:site_name\" content=\"\u5c55\u793a\u4f1a\u52d5\u753b\u3067\u898b\u3064\u3051\u308b\u65b0\u88fd\u54c1\u30fb\u6700\u65b0\u6280\u8853\uff5c\u30a4\u30f3\u30bf\u30fc\u30cd\u30c3\u30c8\u5c55\u793a\u4f1a.tv\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tenji.tv\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-16T11:57:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-09T02:14:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tenji.tv\/japan\/wp-content\/uploads\/2015\/09\/2015-3drvl6540.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u30a4\u30f3\u30bf\u30fc\u30cd\u30c3\u30c8\u5c55\u793a\u4f1a.tv \u7de8\u96c6\u90e8\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u57f7\u7b46\u8005\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u30a4\u30f3\u30bf\u30fc\u30cd\u30c3\u30c8\u5c55\u793a\u4f1a.tv \u7de8\u96c6\u90e8\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tenji.tv\\\/japan\\\/video\\\/2015\\\/measuring-technology-expo_2015\\\/measuring-technology-expo_2015-exhibitor\\\/%e6%b8%ac%e5%ae%9a%e8%a8%88%e6%b8%ac%e5%b1%95-2015-%e5%8d%93%e4%b8%8a%e5%9e%8b%e9%ab%98%e9%80%9f3d%e3%82%b9%e3%82%ad%e3%83%a3%e3%83%8a%e3%80%8crvl6540%e3%80%8d-%e6%97%a5%e6%9c%ac%e9%9b%bb%e7%94%a3\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tenji.tv\\\/japan\\\/video\\\/2015\\\/measuring-technology-expo_2015\\\/measuring-technology-expo_2015-exhibitor\\\/%e6%b8%ac%e5%ae%9a%e8%a8%88%e6%b8%ac%e5%b1%95-2015-%e5%8d%93%e4%b8%8a%e5%9e%8b%e9%ab%98%e9%80%9f3d%e3%82%b9%e3%82%ad%e3%83%a3%e3%83%8a%e3%80%8crvl6540%e3%80%8d-%e6%97%a5%e6%9c%ac%e9%9b%bb%e7%94%a3\\\/\"},\"author\":{\"name\":\"\u30a4\u30f3\u30bf\u30fc\u30cd\u30c3\u30c8\u5c55\u793a\u4f1a.tv \u7de8\u96c6\u90e8\",\"@id\":\"https:\\\/\\\/www.tenji.tv\\\/japan\\\/#\\\/schema\\\/person\\\/f816f3d77548ff7d5c7f967065af19d6\"},\"headline\":\"[\u6e2c\u5b9a\u8a08\u6e2c\u5c55 2015] \u5353\u4e0a\u578b\u9ad8\u901f3D\u30b9\u30ad\u30e3\u30ca\u300cRVL6540\u300d - \u65e5\u672c\u96fb\u7523\u30c8\u30fc\u30bd\u30af\u682a\u5f0f\u4f1a\u793e\",\"datePublished\":\"2015-09-16T11:57:56+00:00\",\"dateModified\":\"2019-05-09T02:14:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tenji.tv\\\/japan\\\/video\\\/2015\\\/measuring-technology-expo_2015\\\/measuring-technology-expo_2015-exhibitor\\\/%e6%b8%ac%e5%ae%9a%e8%a8%88%e6%b8%ac%e5%b1%95-2015-%e5%8d%93%e4%b8%8a%e5%9e%8b%e9%ab%98%e9%80%9f3d%e3%82%b9%e3%82%ad%e3%83%a3%e3%83%8a%e3%80%8crvl6540%e3%80%8d-%e6%97%a5%e6%9c%ac%e9%9b%bb%e7%94%a3\\\/\"},\"wordCount\":12,\"image\":{\"@id\":\"https:\\\/\\\/www.tenji.tv\\\/japan\\\/video\\\/2015\\\/measuring-technology-expo_2015\\\/measuring-technology-expo_2015-exhibitor\\\/%e6%b8%ac%e5%ae%9a%e8%a8%88%e6%b8%ac%e5%b1%95-2015-%e5%8d%93%e4%b8%8a%e5%9e%8b%e9%ab%98%e9%80%9f3d%e3%82%b9%e3%82%ad%e3%83%a3%e3%83%8a%e3%80%8crvl6540%e3%80%8d-%e6%97%a5%e6%9c%ac%e9%9b%bb%e7%94%a3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tenji.tv\\\/japan\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/2015-3drvl6540.jpg\",\"keywords\":[\"\u60c5\u5831\u30fb\u901a\u4fe1\",\"\u6a5f\u68b0\u30fb\u5de5\u696d\u6280\u8853\"],\"articleSection\":[\"measuring-technology-expo_2015-\u51fa\u5c55\u8005\"],\"inLanguage\":\"ja\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tenji.tv\\\/japan\\\/video\\\/2015\\\/measuring-technology-expo_2015\\\/measuring-technology-expo_2015-exhibitor\\\/%e6%b8%ac%e5%ae%9a%e8%a8%88%e6%b8%ac%e5%b1%95-2015-%e5%8d%93%e4%b8%8a%e5%9e%8b%e9%ab%98%e9%80%9f3d%e3%82%b9%e3%82%ad%e3%83%a3%e3%83%8a%e3%80%8crvl6540%e3%80%8d-%e6%97%a5%e6%9c%ac%e9%9b%bb%e7%94%a3\\\/\",\"url\":\"https:\\\/\\\/www.tenji.tv\\\/japan\\\/video\\\/2015\\\/measuring-technology-expo_2015\\\/measuring-technology-expo_2015-exhibitor\\\/%e6%b8%ac%e5%ae%9a%e8%a8%88%e6%b8%ac%e5%b1%95-2015-%e5%8d%93%e4%b8%8a%e5%9e%8b%e9%ab%98%e9%80%9f3d%e3%82%b9%e3%82%ad%e3%83%a3%e3%83%8a%e3%80%8crvl6540%e3%80%8d-%e6%97%a5%e6%9c%ac%e9%9b%bb%e7%94%a3\\\/\",\"name\":\"[\u6e2c\u5b9a\u8a08\u6e2c\u5c55 2015] \u5353\u4e0a\u578b\u9ad8\u901f3D\u30b9\u30ad\u30e3\u30ca\u300cRVL6540\u300d - \u65e5\u672c\u96fb\u7523\u30c8\u30fc\u30bd\u30af\u682a\u5f0f\u4f1a\u793e \uff5c\u5c55\u793a\u4f1a\u52d5\u753b\uff5c\u30a4\u30f3\u30bf\u30fc\u30cd\u30c3\u30c8\u5c55\u793a\u4f1a.tv\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tenji.tv\\\/japan\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tenji.tv\\\/japan\\\/video\\\/2015\\\/measuring-technology-expo_2015\\\/measuring-technology-expo_2015-exhibitor\\\/%e6%b8%ac%e5%ae%9a%e8%a8%88%e6%b8%ac%e5%b1%95-2015-%e5%8d%93%e4%b8%8a%e5%9e%8b%e9%ab%98%e9%80%9f3d%e3%82%b9%e3%82%ad%e3%83%a3%e3%83%8a%e3%80%8crvl6540%e3%80%8d-%e6%97%a5%e6%9c%ac%e9%9b%bb%e7%94%a3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tenji.tv\\\/japan\\\/video\\\/2015\\\/measuring-technology-expo_2015\\\/measuring-technology-expo_2015-exhibitor\\\/%e6%b8%ac%e5%ae%9a%e8%a8%88%e6%b8%ac%e5%b1%95-2015-%e5%8d%93%e4%b8%8a%e5%9e%8b%e9%ab%98%e9%80%9f3d%e3%82%b9%e3%82%ad%e3%83%a3%e3%83%8a%e3%80%8crvl6540%e3%80%8d-%e6%97%a5%e6%9c%ac%e9%9b%bb%e7%94%a3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tenji.tv\\\/japan\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/2015-3drvl6540.jpg\",\"datePublished\":\"2015-09-16T11:57:56+00:00\",\"dateModified\":\"2019-05-09T02:14:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.tenji.tv\\\/japan\\\/#\\\/schema\\\/person\\\/f816f3d77548ff7d5c7f967065af19d6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tenji.tv\\\/japan\\\/video\\\/2015\\\/measuring-technology-expo_2015\\\/measuring-technology-expo_2015-exhibitor\\\/%e6%b8%ac%e5%ae%9a%e8%a8%88%e6%b8%ac%e5%b1%95-2015-%e5%8d%93%e4%b8%8a%e5%9e%8b%e9%ab%98%e9%80%9f3d%e3%82%b9%e3%82%ad%e3%83%a3%e3%83%8a%e3%80%8crvl6540%e3%80%8d-%e6%97%a5%e6%9c%ac%e9%9b%bb%e7%94%a3\\\/#breadcrumb\"},\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tenji.tv\\\/japan\\\/video\\\/2015\\\/measuring-technology-expo_2015\\\/measuring-technology-expo_2015-exhibitor\\\/%e6%b8%ac%e5%ae%9a%e8%a8%88%e6%b8%ac%e5%b1%95-2015-%e5%8d%93%e4%b8%8a%e5%9e%8b%e9%ab%98%e9%80%9f3d%e3%82%b9%e3%82%ad%e3%83%a3%e3%83%8a%e3%80%8crvl6540%e3%80%8d-%e6%97%a5%e6%9c%ac%e9%9b%bb%e7%94%a3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\\\/\\\/www.tenji.tv\\\/japan\\\/video\\\/2015\\\/measuring-technology-expo_2015\\\/measuring-technology-expo_2015-exhibitor\\\/%e6%b8%ac%e5%ae%9a%e8%a8%88%e6%b8%ac%e5%b1%95-2015-%e5%8d%93%e4%b8%8a%e5%9e%8b%e9%ab%98%e9%80%9f3d%e3%82%b9%e3%82%ad%e3%83%a3%e3%83%8a%e3%80%8crvl6540%e3%80%8d-%e6%97%a5%e6%9c%ac%e9%9b%bb%e7%94%a3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tenji.tv\\\/japan\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/2015-3drvl6540.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tenji.tv\\\/japan\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/2015-3drvl6540.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tenji.tv\\\/japan\\\/video\\\/2015\\\/measuring-technology-expo_2015\\\/measuring-technology-expo_2015-exhibitor\\\/%e6%b8%ac%e5%ae%9a%e8%a8%88%e6%b8%ac%e5%b1%95-2015-%e5%8d%93%e4%b8%8a%e5%9e%8b%e9%ab%98%e9%80%9f3d%e3%82%b9%e3%82%ad%e3%83%a3%e3%83%8a%e3%80%8crvl6540%e3%80%8d-%e6%97%a5%e6%9c%ac%e9%9b%bb%e7%94%a3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u30db\u30fc\u30e0\",\"item\":\"https:\\\/\\\/www.tenji.tv\\\/japan\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[\u6e2c\u5b9a\u8a08\u6e2c\u5c55 2015] \u5353\u4e0a\u578b\u9ad8\u901f3D\u30b9\u30ad\u30e3\u30ca\u300cRVL6540\u300d - \u65e5\u672c\u96fb\u7523\u30c8\u30fc\u30bd\u30af\u682a\u5f0f\u4f1a\u793e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tenji.tv\\\/japan\\\/#website\",\"url\":\"https:\\\/\\\/www.tenji.tv\\\/japan\\\/\",\"name\":\"\u5c55\u793a\u4f1a\u52d5\u753b\u3067\u898b\u3064\u3051\u308b\u65b0\u88fd\u54c1\u30fb\u6700\u65b0\u6280\u8853\uff5c\u30a4\u30f3\u30bf\u30fc\u30cd\u30c3\u30c8\u5c55\u793a\u4f1a.tv\",\"description\":\"\u56fd\u5185\u5916\u306e\u5c55\u793a\u4f1a\u3067\u767a\u8868\u3055\u308c\u305f\u88fd\u54c1\u30fb\u6280\u8853\u3092\u52d5\u753b\u3067\u7d39\u4ecb\u3002\u51fa\u5c55\u4f01\u696d\u60c5\u5831\u3092\u5206\u91ce\u5225\u306b\u63a2\u305b\u308b\u5c55\u793a\u4f1a\u52d5\u753b\u30e1\u30c7\u30a3\u30a2\u3002\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tenji.tv\\\/japan\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ja\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tenji.tv\\\/japan\\\/#\\\/schema\\\/person\\\/f816f3d77548ff7d5c7f967065af19d6\",\"name\":\"\u30a4\u30f3\u30bf\u30fc\u30cd\u30c3\u30c8\u5c55\u793a\u4f1a.tv \u7de8\u96c6\u90e8\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\\\/\\\/www.tenji.tv\\\/japan\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/3d4b2bd2a2c632718f5d654508dd1423.tv-\u7de8\u96c6\u90e8_avatar-96x96.png\",\"url\":\"https:\\\/\\\/www.tenji.tv\\\/japan\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/3d4b2bd2a2c632718f5d654508dd1423.tv-\u7de8\u96c6\u90e8_avatar-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.tenji.tv\\\/japan\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/3d4b2bd2a2c632718f5d654508dd1423.tv-\u7de8\u96c6\u90e8_avatar-96x96.png\",\"caption\":\"\u30a4\u30f3\u30bf\u30fc\u30cd\u30c3\u30c8\u5c55\u793a\u4f1a.tv \u7de8\u96c6\u90e8\"},\"description\":\"1) \u4e16\u754c\u4e2d\u306e\u5c55\u793a\u4f1a\u306e\u6700\u65b0\u60c5\u5831\u3092\u30e1\u30fc\u30eb\u3067\u304a\u77e5\u3089\u305b\u3057\u307e\u3059\u3002\u30e1\u30eb\u30de\u30ac\u306e\u767b\u9332\u306f\u3053\u3061\u3089\u3002 2) \u51fa\u5c55\u3092\u3054\u691c\u8a0e\u3067\u3059\u304b\uff1f\u51fa\u5c55\u30b5\u30dd\u30fc\u30c8\u3092\u3054\u5229\u7528\u304f\u3060\u3055\u3044\u3002\u56fd\u5185\u51fa\u5c55\u30fb\u30d6\u30fc\u30b9\u30d7\u30e9\u30f3\u30cb\u30f3\u30b0 \\\/ \u6d77\u5916\u51fa\u5c55\u652f\u63f4 3) \u5c55\u793a\u4f1a\u306e\u51fa\u5c55\u306f\u3001\u4f1a\u5834\u3060\u3051\u3067\u7d42\u308f\u3089\u305b\u3066\u306f\u3044\u3051\u307e\u305b\u3093\u3002\u30aa\u30f3\u30e9\u30a4\u30f3\u3067\u6d3b\u7528\u3059\u308b\u300c\u5c55\u793a\u4f1a\u52d5\u753b\u30de\u30fc\u30b1\u30c6\u30a3\u30f3\u30b0\u300d\u306f\u3053\u3061\u3089\"}]}<\/script>\n<meta property=\"og:video\" content=\"https:\/\/www.youtube.com\/embed\/TUVcPnoTG2o\" \/>\n<meta property=\"og:video:type\" content=\"text\/html\" \/>\n<meta property=\"og:video:duration\" content=\"151\" \/>\n<meta property=\"og:video:width\" content=\"480\" \/>\n<meta property=\"og:video:height\" content=\"270\" \/>\n<meta property=\"ya:ovs:adult\" content=\"false\" \/>\n<meta property=\"ya:ovs:allow_embed\" content=\"true\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[\u6e2c\u5b9a\u8a08\u6e2c\u5c55 2015] \u5353\u4e0a\u578b\u9ad8\u901f3D\u30b9\u30ad\u30e3\u30ca\u300cRVL6540\u300d - \u65e5\u672c\u96fb\u7523\u30c8\u30fc\u30bd\u30af\u682a\u5f0f\u4f1a\u793e \uff5c\u5c55\u793a\u4f1a\u52d5\u753b\uff5c\u30a4\u30f3\u30bf\u30fc\u30cd\u30c3\u30c8\u5c55\u793a\u4f1a.tv","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tenji.tv\/japan\/video\/2015\/measuring-technology-expo_2015\/measuring-technology-expo_2015-exhibitor\/\u6e2c\u5b9a\u8a08\u6e2c\u5c55-2015-\u5353\u4e0a\u578b\u9ad8\u901f3d\u30b9\u30ad\u30e3\u30ca\u300crvl6540\u300d-\u65e5\u672c\u96fb\u7523\/","og_locale":"ja_JP","og_type":"article","og_title":"[\u6e2c\u5b9a\u8a08\u6e2c\u5c55 2015] \u5353\u4e0a\u578b\u9ad8\u901f3D\u30b9\u30ad\u30e3\u30ca\u300cRVL6540\u300d - \u65e5\u672c\u96fb\u7523\u30c8\u30fc\u30bd\u30af\u682a\u5f0f\u4f1a\u793e \uff5c\u5c55\u793a\u4f1a\u52d5\u753b\uff5c\u30a4\u30f3\u30bf\u30fc\u30cd\u30c3\u30c8\u5c55\u793a\u4f1a.tv","og_description":"\u65e5\u672c\u96fb\u7523\u30c8\u30fc\u30bd\u30af\u682a\u5f0f\u4f1a\u793e\u306f\u6e2c\u5b9a\u8a08\u6e2c\u5c55 2015\u306b\u3066\u3001\u5353\u4e0a\u578b\u9ad8\u901f3D\u30b9\u30ad\u30e3\u30ca\u300cRVL6540\u300d\u3092\u51fa\u5c55\u3002 \u30e9\u30a4\u30f3\u30ec\u30fc\u30b6\u30fc\u306b\u3088\u308b\u5149\u5207\u65ad\u65b9\u5f0f\u3092\u63a1\u7528\u3057\u305f\u5353\u4e0a\u578b\u9ad8\u901f3D\u30b9\u30ad\u30e3\u30ca\u30fc\u3092\u7d39\u4ecb\u3002 \u8a73\u7d30\u306f\u30a4\u30f3\u30bf\u30fc\u30cd\u30c3\u30c8\u5c55\u793a\u4f1a.tv\u3078\uff01 htt [&hellip;]","og_url":"https:\/\/www.tenji.tv\/japan\/video\/2015\/measuring-technology-expo_2015\/measuring-technology-expo_2015-exhibitor\/\u6e2c\u5b9a\u8a08\u6e2c\u5c55-2015-\u5353\u4e0a\u578b\u9ad8\u901f3d\u30b9\u30ad\u30e3\u30ca\u300crvl6540\u300d-\u65e5\u672c\u96fb\u7523\/","og_site_name":"\u5c55\u793a\u4f1a\u52d5\u753b\u3067\u898b\u3064\u3051\u308b\u65b0\u88fd\u54c1\u30fb\u6700\u65b0\u6280\u8853\uff5c\u30a4\u30f3\u30bf\u30fc\u30cd\u30c3\u30c8\u5c55\u793a\u4f1a.tv","article_publisher":"https:\/\/www.facebook.com\/tenji.tv","article_published_time":"2015-09-16T11:57:56+00:00","article_modified_time":"2019-05-09T02:14:10+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.tenji.tv\/japan\/wp-content\/uploads\/2015\/09\/2015-3drvl6540.jpg","type":"image\/jpeg"}],"author":"\u30a4\u30f3\u30bf\u30fc\u30cd\u30c3\u30c8\u5c55\u793a\u4f1a.tv \u7de8\u96c6\u90e8","twitter_card":"summary_large_image","twitter_misc":{"\u57f7\u7b46\u8005":"\u30a4\u30f3\u30bf\u30fc\u30cd\u30c3\u30c8\u5c55\u793a\u4f1a.tv \u7de8\u96c6\u90e8"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tenji.tv\/japan\/video\/2015\/measuring-technology-expo_2015\/measuring-technology-expo_2015-exhibitor\/%e6%b8%ac%e5%ae%9a%e8%a8%88%e6%b8%ac%e5%b1%95-2015-%e5%8d%93%e4%b8%8a%e5%9e%8b%e9%ab%98%e9%80%9f3d%e3%82%b9%e3%82%ad%e3%83%a3%e3%83%8a%e3%80%8crvl6540%e3%80%8d-%e6%97%a5%e6%9c%ac%e9%9b%bb%e7%94%a3\/#article","isPartOf":{"@id":"https:\/\/www.tenji.tv\/japan\/video\/2015\/measuring-technology-expo_2015\/measuring-technology-expo_2015-exhibitor\/%e6%b8%ac%e5%ae%9a%e8%a8%88%e6%b8%ac%e5%b1%95-2015-%e5%8d%93%e4%b8%8a%e5%9e%8b%e9%ab%98%e9%80%9f3d%e3%82%b9%e3%82%ad%e3%83%a3%e3%83%8a%e3%80%8crvl6540%e3%80%8d-%e6%97%a5%e6%9c%ac%e9%9b%bb%e7%94%a3\/"},"author":{"name":"\u30a4\u30f3\u30bf\u30fc\u30cd\u30c3\u30c8\u5c55\u793a\u4f1a.tv \u7de8\u96c6\u90e8","@id":"https:\/\/www.tenji.tv\/japan\/#\/schema\/person\/f816f3d77548ff7d5c7f967065af19d6"},"headline":"[\u6e2c\u5b9a\u8a08\u6e2c\u5c55 2015] \u5353\u4e0a\u578b\u9ad8\u901f3D\u30b9\u30ad\u30e3\u30ca\u300cRVL6540\u300d - \u65e5\u672c\u96fb\u7523\u30c8\u30fc\u30bd\u30af\u682a\u5f0f\u4f1a\u793e","datePublished":"2015-09-16T11:57:56+00:00","dateModified":"2019-05-09T02:14:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tenji.tv\/japan\/video\/2015\/measuring-technology-expo_2015\/measuring-technology-expo_2015-exhibitor\/%e6%b8%ac%e5%ae%9a%e8%a8%88%e6%b8%ac%e5%b1%95-2015-%e5%8d%93%e4%b8%8a%e5%9e%8b%e9%ab%98%e9%80%9f3d%e3%82%b9%e3%82%ad%e3%83%a3%e3%83%8a%e3%80%8crvl6540%e3%80%8d-%e6%97%a5%e6%9c%ac%e9%9b%bb%e7%94%a3\/"},"wordCount":12,"image":{"@id":"https:\/\/www.tenji.tv\/japan\/video\/2015\/measuring-technology-expo_2015\/measuring-technology-expo_2015-exhibitor\/%e6%b8%ac%e5%ae%9a%e8%a8%88%e6%b8%ac%e5%b1%95-2015-%e5%8d%93%e4%b8%8a%e5%9e%8b%e9%ab%98%e9%80%9f3d%e3%82%b9%e3%82%ad%e3%83%a3%e3%83%8a%e3%80%8crvl6540%e3%80%8d-%e6%97%a5%e6%9c%ac%e9%9b%bb%e7%94%a3\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tenji.tv\/japan\/wp-content\/uploads\/2015\/09\/2015-3drvl6540.jpg","keywords":["\u60c5\u5831\u30fb\u901a\u4fe1","\u6a5f\u68b0\u30fb\u5de5\u696d\u6280\u8853"],"articleSection":["measuring-technology-expo_2015-\u51fa\u5c55\u8005"],"inLanguage":"ja"},{"@type":"WebPage","@id":"https:\/\/www.tenji.tv\/japan\/video\/2015\/measuring-technology-expo_2015\/measuring-technology-expo_2015-exhibitor\/%e6%b8%ac%e5%ae%9a%e8%a8%88%e6%b8%ac%e5%b1%95-2015-%e5%8d%93%e4%b8%8a%e5%9e%8b%e9%ab%98%e9%80%9f3d%e3%82%b9%e3%82%ad%e3%83%a3%e3%83%8a%e3%80%8crvl6540%e3%80%8d-%e6%97%a5%e6%9c%ac%e9%9b%bb%e7%94%a3\/","url":"https:\/\/www.tenji.tv\/japan\/video\/2015\/measuring-technology-expo_2015\/measuring-technology-expo_2015-exhibitor\/%e6%b8%ac%e5%ae%9a%e8%a8%88%e6%b8%ac%e5%b1%95-2015-%e5%8d%93%e4%b8%8a%e5%9e%8b%e9%ab%98%e9%80%9f3d%e3%82%b9%e3%82%ad%e3%83%a3%e3%83%8a%e3%80%8crvl6540%e3%80%8d-%e6%97%a5%e6%9c%ac%e9%9b%bb%e7%94%a3\/","name":"[\u6e2c\u5b9a\u8a08\u6e2c\u5c55 2015] \u5353\u4e0a\u578b\u9ad8\u901f3D\u30b9\u30ad\u30e3\u30ca\u300cRVL6540\u300d - \u65e5\u672c\u96fb\u7523\u30c8\u30fc\u30bd\u30af\u682a\u5f0f\u4f1a\u793e \uff5c\u5c55\u793a\u4f1a\u52d5\u753b\uff5c\u30a4\u30f3\u30bf\u30fc\u30cd\u30c3\u30c8\u5c55\u793a\u4f1a.tv","isPartOf":{"@id":"https:\/\/www.tenji.tv\/japan\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tenji.tv\/japan\/video\/2015\/measuring-technology-expo_2015\/measuring-technology-expo_2015-exhibitor\/%e6%b8%ac%e5%ae%9a%e8%a8%88%e6%b8%ac%e5%b1%95-2015-%e5%8d%93%e4%b8%8a%e5%9e%8b%e9%ab%98%e9%80%9f3d%e3%82%b9%e3%82%ad%e3%83%a3%e3%83%8a%e3%80%8crvl6540%e3%80%8d-%e6%97%a5%e6%9c%ac%e9%9b%bb%e7%94%a3\/#primaryimage"},"image":{"@id":"https:\/\/www.tenji.tv\/japan\/video\/2015\/measuring-technology-expo_2015\/measuring-technology-expo_2015-exhibitor\/%e6%b8%ac%e5%ae%9a%e8%a8%88%e6%b8%ac%e5%b1%95-2015-%e5%8d%93%e4%b8%8a%e5%9e%8b%e9%ab%98%e9%80%9f3d%e3%82%b9%e3%82%ad%e3%83%a3%e3%83%8a%e3%80%8crvl6540%e3%80%8d-%e6%97%a5%e6%9c%ac%e9%9b%bb%e7%94%a3\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tenji.tv\/japan\/wp-content\/uploads\/2015\/09\/2015-3drvl6540.jpg","datePublished":"2015-09-16T11:57:56+00:00","dateModified":"2019-05-09T02:14:10+00:00","author":{"@id":"https:\/\/www.tenji.tv\/japan\/#\/schema\/person\/f816f3d77548ff7d5c7f967065af19d6"},"breadcrumb":{"@id":"https:\/\/www.tenji.tv\/japan\/video\/2015\/measuring-technology-expo_2015\/measuring-technology-expo_2015-exhibitor\/%e6%b8%ac%e5%ae%9a%e8%a8%88%e6%b8%ac%e5%b1%95-2015-%e5%8d%93%e4%b8%8a%e5%9e%8b%e9%ab%98%e9%80%9f3d%e3%82%b9%e3%82%ad%e3%83%a3%e3%83%8a%e3%80%8crvl6540%e3%80%8d-%e6%97%a5%e6%9c%ac%e9%9b%bb%e7%94%a3\/#breadcrumb"},"inLanguage":"ja","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tenji.tv\/japan\/video\/2015\/measuring-technology-expo_2015\/measuring-technology-expo_2015-exhibitor\/%e6%b8%ac%e5%ae%9a%e8%a8%88%e6%b8%ac%e5%b1%95-2015-%e5%8d%93%e4%b8%8a%e5%9e%8b%e9%ab%98%e9%80%9f3d%e3%82%b9%e3%82%ad%e3%83%a3%e3%83%8a%e3%80%8crvl6540%e3%80%8d-%e6%97%a5%e6%9c%ac%e9%9b%bb%e7%94%a3\/"]}]},{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/www.tenji.tv\/japan\/video\/2015\/measuring-technology-expo_2015\/measuring-technology-expo_2015-exhibitor\/%e6%b8%ac%e5%ae%9a%e8%a8%88%e6%b8%ac%e5%b1%95-2015-%e5%8d%93%e4%b8%8a%e5%9e%8b%e9%ab%98%e9%80%9f3d%e3%82%b9%e3%82%ad%e3%83%a3%e3%83%8a%e3%80%8crvl6540%e3%80%8d-%e6%97%a5%e6%9c%ac%e9%9b%bb%e7%94%a3\/#primaryimage","url":"https:\/\/www.tenji.tv\/japan\/wp-content\/uploads\/2015\/09\/2015-3drvl6540.jpg","contentUrl":"https:\/\/www.tenji.tv\/japan\/wp-content\/uploads\/2015\/09\/2015-3drvl6540.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.tenji.tv\/japan\/video\/2015\/measuring-technology-expo_2015\/measuring-technology-expo_2015-exhibitor\/%e6%b8%ac%e5%ae%9a%e8%a8%88%e6%b8%ac%e5%b1%95-2015-%e5%8d%93%e4%b8%8a%e5%9e%8b%e9%ab%98%e9%80%9f3d%e3%82%b9%e3%82%ad%e3%83%a3%e3%83%8a%e3%80%8crvl6540%e3%80%8d-%e6%97%a5%e6%9c%ac%e9%9b%bb%e7%94%a3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u30db\u30fc\u30e0","item":"https:\/\/www.tenji.tv\/japan\/"},{"@type":"ListItem","position":2,"name":"[\u6e2c\u5b9a\u8a08\u6e2c\u5c55 2015] \u5353\u4e0a\u578b\u9ad8\u901f3D\u30b9\u30ad\u30e3\u30ca\u300cRVL6540\u300d - \u65e5\u672c\u96fb\u7523\u30c8\u30fc\u30bd\u30af\u682a\u5f0f\u4f1a\u793e"}]},{"@type":"WebSite","@id":"https:\/\/www.tenji.tv\/japan\/#website","url":"https:\/\/www.tenji.tv\/japan\/","name":"\u5c55\u793a\u4f1a\u52d5\u753b\u3067\u898b\u3064\u3051\u308b\u65b0\u88fd\u54c1\u30fb\u6700\u65b0\u6280\u8853\uff5c\u30a4\u30f3\u30bf\u30fc\u30cd\u30c3\u30c8\u5c55\u793a\u4f1a.tv","description":"\u56fd\u5185\u5916\u306e\u5c55\u793a\u4f1a\u3067\u767a\u8868\u3055\u308c\u305f\u88fd\u54c1\u30fb\u6280\u8853\u3092\u52d5\u753b\u3067\u7d39\u4ecb\u3002\u51fa\u5c55\u4f01\u696d\u60c5\u5831\u3092\u5206\u91ce\u5225\u306b\u63a2\u305b\u308b\u5c55\u793a\u4f1a\u52d5\u753b\u30e1\u30c7\u30a3\u30a2\u3002","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tenji.tv\/japan\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ja"},{"@type":"Person","@id":"https:\/\/www.tenji.tv\/japan\/#\/schema\/person\/f816f3d77548ff7d5c7f967065af19d6","name":"\u30a4\u30f3\u30bf\u30fc\u30cd\u30c3\u30c8\u5c55\u793a\u4f1a.tv \u7de8\u96c6\u90e8","image":{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/www.tenji.tv\/japan\/wp-content\/uploads\/2025\/01\/3d4b2bd2a2c632718f5d654508dd1423.tv-\u7de8\u96c6\u90e8_avatar-96x96.png","url":"https:\/\/www.tenji.tv\/japan\/wp-content\/uploads\/2025\/01\/3d4b2bd2a2c632718f5d654508dd1423.tv-\u7de8\u96c6\u90e8_avatar-96x96.png","contentUrl":"https:\/\/www.tenji.tv\/japan\/wp-content\/uploads\/2025\/01\/3d4b2bd2a2c632718f5d654508dd1423.tv-\u7de8\u96c6\u90e8_avatar-96x96.png","caption":"\u30a4\u30f3\u30bf\u30fc\u30cd\u30c3\u30c8\u5c55\u793a\u4f1a.tv \u7de8\u96c6\u90e8"},"description":"1) \u4e16\u754c\u4e2d\u306e\u5c55\u793a\u4f1a\u306e\u6700\u65b0\u60c5\u5831\u3092\u30e1\u30fc\u30eb\u3067\u304a\u77e5\u3089\u305b\u3057\u307e\u3059\u3002\u30e1\u30eb\u30de\u30ac\u306e\u767b\u9332\u306f\u3053\u3061\u3089\u3002 2) \u51fa\u5c55\u3092\u3054\u691c\u8a0e\u3067\u3059\u304b\uff1f\u51fa\u5c55\u30b5\u30dd\u30fc\u30c8\u3092\u3054\u5229\u7528\u304f\u3060\u3055\u3044\u3002\u56fd\u5185\u51fa\u5c55\u30fb\u30d6\u30fc\u30b9\u30d7\u30e9\u30f3\u30cb\u30f3\u30b0 \/ \u6d77\u5916\u51fa\u5c55\u652f\u63f4 3) \u5c55\u793a\u4f1a\u306e\u51fa\u5c55\u306f\u3001\u4f1a\u5834\u3060\u3051\u3067\u7d42\u308f\u3089\u305b\u3066\u306f\u3044\u3051\u307e\u305b\u3093\u3002\u30aa\u30f3\u30e9\u30a4\u30f3\u3067\u6d3b\u7528\u3059\u308b\u300c\u5c55\u793a\u4f1a\u52d5\u753b\u30de\u30fc\u30b1\u30c6\u30a3\u30f3\u30b0\u300d\u306f\u3053\u3061\u3089"}]},"og_video":"https:\/\/www.youtube.com\/embed\/TUVcPnoTG2o","og_video_type":"text\/html","og_video_duration":"151","og_video_width":"480","og_video_height":"270","ya_ovs_adult":"false","ya_ovs_allow_embed":"true"},"cmb2":{"poster_feature_image":{"vid_m_player_background":"","vid_m_poster_image":"","vid_m_poster_image_id":""},"gif_feature_image":{"vid_m_gif_image":"","vid_m_gif_image_id":""},"video_movie_settings":{"vid_m_director":"","vid_m_actor":"","vid_m_imdb_ratings":"","vid_m_amazon_associates":"","vid_m_vid_tmdb_movie":"","vid_m_vid_tmdb_tv_shows":"","vid_m_vid_tmdb_thumb":""},"vid_ads_m_videoads_settings_post":{"vid_ads_m_video_ads":"","vid_ads_m_video_ads_type":"","vid_ads_m_group_google_ima":"","vid_ads_m_group_image":"","vid_ads_m_group_html5_video":"","vid_ads_m_group_html":"","vid_ads_m_vpaid_mode":"","vid_ads_m_vast_preroll":"","vid_ads_m_vast_postroll":"","vid_ads_m_vast_pauseroll":"","vid_ads_m_vast_midroll":"","vid_ads_m_group_dynamic":"","vid_ads_m_time_to_show_ads":"","vid_ads_m_time_skip_ads":"","vid_ads_m_time_to_hide_ads":""},"feature_image_settings":{"feature_image_position":""},"video_player_settings":{"single_video_style":"","video_player_position":"","vm_video_url_btn_choose":"","vm_video_url_btn_choose_id":"","vm_video_url":"https:\/\/youtu.be\/TUVcPnoTG2o","vm_video_ratio":"","vm_video_ratio_mobile":"","video_player_library":"","plyr_player":"","video_streaming":"","vm_video_shortcode":"","vm_video_timelapse":"","vm_media_subtitles":"","vm_media_sources":"","vid_vtt_preview":"","vid_vtt_preview_vtt_file":"","vid_vtt_preview_vtt_file_id":"","vid_vtt_preview_sprite_image":"","vid_vtt_preview_sprite_image_id":"","vid_auto_play":"","vid_preview_mode":"","vm_video_trailer_manl_url":"","vm_screenshot_preview":"","vid_tags":"","vid_p_sync_playlist":"","vid_c_sync_channel":"","get_post_format":"","multiple_links_structure":"","multi_links_title":"","original_video_title":"","multi_links_series":"","vm_video_multi_links":"","vm_duration":"02:31","vid_social_locker":"off","vid_locker_mode":"","vid_social_locker_id":"","vid_social_email_locker_id":"","vid_social_signin_locker_id":"","sv_login_to_watch":"","vid_membership_action":"content-video","vm_video_trailer_url":"","vid_download_type":"free","vid_download_target":"","vid_woo_product":"","vid_download_mode":"","vid_download_mode_trailer":"","vm_media_download":"","user_rating":"","user_rating_position":"","user_rating_mode":"","user_rating_multi_sets":"","ads_above_single_player":""},"video_auto_fetch_settings":{"vm_video_fetch":"off"},"video_fake_views_likes":{"vm_fake_views":"","vm_fake_likes":"","vm_fake_dislikes":""},"gallery_settings":{"gallery_position":""},"quote_settings":{"quote_position":""},"post_options":{"main_layout":"","main_logo":"","main_logo_id":"","main_logo_retina":"","main_logo_retina_id":"","main_logo_mobile":"","main_logo_mobile_id":"","main_logo_mobile_retina":"","main_logo_mobile_retina_id":"","sticky_logo":"","sticky_logo_id":"","sticky_logo_retina":"","sticky_logo_retina_id":"","main_nav_layout":"","header_background":"","theme_sidebar":"","single_post_comment_type":"","theme_background":""}},"_links":{"self":[{"href":"https:\/\/www.tenji.tv\/japan\/wp-json\/wp\/v2\/posts\/18443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tenji.tv\/japan\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tenji.tv\/japan\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tenji.tv\/japan\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tenji.tv\/japan\/wp-json\/wp\/v2\/comments?post=18443"}],"version-history":[{"count":0,"href":"https:\/\/www.tenji.tv\/japan\/wp-json\/wp\/v2\/posts\/18443\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tenji.tv\/japan\/wp-json\/wp\/v2\/media\/18461"}],"wp:attachment":[{"href":"https:\/\/www.tenji.tv\/japan\/wp-json\/wp\/v2\/media?parent=18443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tenji.tv\/japan\/wp-json\/wp\/v2\/categories?post=18443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tenji.tv\/japan\/wp-json\/wp\/v2\/tags?post=18443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}